{"id":6122,"count":1,"description":"","link":"https:\/\/silko.it\/en\/prodotto\/nebg74gms\/","name":"NEBG74GMS","slug":"nebg74gms","taxonomy":"product_cat","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>NEBG74GMS Archivi - Silko<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NEBG74GMS Archivi - Silko\" \/>\n<meta property=\"og:url\" content=\"https:\/\/silko.it\/en\/prodotto\/16306460-nebg74glrx-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Silko\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/silko.it\/en\/prodotto\/16306460-nebg74glrx-en\/\",\"url\":\"https:\/\/silko.it\/en\/prodotto\/16306460-nebg74glrx-en\/\",\"name\":\"NEBG74GMS Archivi - Silko\",\"isPartOf\":{\"@id\":\"https:\/\/silko.it\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/silko.it\/en\/prodotto\/16306460-nebg74glrx-en\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/silko.it\/en\/prodotto\/16306460-nebg74glrx-en\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/silko.it\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NEBG74GLRX\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/silko.it\/#website\",\"url\":\"https:\/\/silko.it\/\",\"name\":\"https:\/\/silko.it\/\",\"description\":\"Cucine professionali e arredi per la ristorazione\",\"publisher\":{\"@id\":\"https:\/\/silko.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/silko.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/silko.it\/#organization\",\"name\":\"Silko - Cucine professionali e attrezzature per la ristorazione\",\"url\":\"https:\/\/silko.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/silko.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/silko.it\/wp-content\/uploads\/2023\/08\/silko-logo.webp\",\"contentUrl\":\"https:\/\/silko.it\/wp-content\/uploads\/2023\/08\/silko-logo.webp\",\"width\":186,\"height\":56,\"caption\":\"Silko - Cucine professionali e attrezzature per la ristorazione\"},\"image\":{\"@id\":\"https:\/\/silko.it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/SilkoAli\/\",\"https:\/\/www.instagram.com\/silko_ali\/\",\"https:\/\/www.linkedin.com\/company\/silko-ali-s.p.a.\/\",\"https:\/\/www.youtube.com\/user\/SilkoAli\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NEBG74GMS Archivi - Silko","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"NEBG74GMS Archivi - Silko","og_url":"https:\/\/silko.it\/en\/prodotto\/16306460-nebg74glrx-en\/","og_site_name":"Silko","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/silko.it\/en\/prodotto\/16306460-nebg74glrx-en\/","url":"https:\/\/silko.it\/en\/prodotto\/16306460-nebg74glrx-en\/","name":"NEBG74GMS Archivi - Silko","isPartOf":{"@id":"https:\/\/silko.it\/#website"},"breadcrumb":{"@id":"https:\/\/silko.it\/en\/prodotto\/16306460-nebg74glrx-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/silko.it\/en\/prodotto\/16306460-nebg74glrx-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/silko.it\/en\/"},{"@type":"ListItem","position":2,"name":"NEBG74GLRX"}]},{"@type":"WebSite","@id":"https:\/\/silko.it\/#website","url":"https:\/\/silko.it\/","name":"https:\/\/silko.it\/","description":"Cucine professionali e arredi per la ristorazione","publisher":{"@id":"https:\/\/silko.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/silko.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/silko.it\/#organization","name":"Silko - Cucine professionali e attrezzature per la ristorazione","url":"https:\/\/silko.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/silko.it\/#\/schema\/logo\/image\/","url":"https:\/\/silko.it\/wp-content\/uploads\/2023\/08\/silko-logo.webp","contentUrl":"https:\/\/silko.it\/wp-content\/uploads\/2023\/08\/silko-logo.webp","width":186,"height":56,"caption":"Silko - Cucine professionali e attrezzature per la ristorazione"},"image":{"@id":"https:\/\/silko.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SilkoAli\/","https:\/\/www.instagram.com\/silko_ali\/","https:\/\/www.linkedin.com\/company\/silko-ali-s.p.a.\/","https:\/\/www.youtube.com\/user\/SilkoAli"]}]}},"_links":{"self":[{"href":"https:\/\/silko.it\/en\/wp-json\/wp\/v2\/product_cat\/6122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/silko.it\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/silko.it\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/silko.it\/en\/wp-json\/wp\/v2\/product?product_cat=6122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}