{"id":6396,"date":"2023-10-19T14:31:14","date_gmt":"2023-10-19T14:31:14","guid":{"rendered":"https:\/\/silko.lithos.it\/news\/news\/"},"modified":"2024-07-24T08:16:23","modified_gmt":"2024-07-24T08:16:23","slug":"news-old","status":"publish","type":"page","link":"https:\/\/silko.it\/fr\/news-old\/","title":{"rendered":"News Old"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"6396\" class=\"elementor elementor-6396 elementor-3297\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aa84f18 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aa84f18\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c1c91c2\" data-id=\"c1c91c2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7841a3c elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7841a3c\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f9d9a79\" data-id=\"f9d9a79\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ca0c66 elementor-widget elementor-widget-heading\" data-id=\"4ca0c66\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">News<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e93dea4 elementor-widget elementor-widget-shortcode\" data-id=\"e93dea4\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">    \t<style type=\"text\/css\">\r\n\r\n    \t\t*{\r\n    \t\t\tfont-family: \"Open Sans\";\r\n    \t\t}\r\n    \t\t.post-date{\r\n    \t\t\tcolor: #D7761E !important;\r\n    \t\t\tfont-size: 20px;\r\n    \t\t}\r\n\r\n    \t\t.post-info{\r\n    \t\t\tcolor: #002940 !important;\r\n    \t\t}\r\n\r\n    \t\t.post-read-button{\r\n    \t\t\tbackground-color: #00000000 !important;\r\n    \t\t\tcolor: #002940 !important;\r\n    \t\t\tpadding: 15px 21px;\r\n    \t\t\tborder: 1px solid #002940 !important;\r\n    \t\t\tborder-radius: 0px;\r\n    \t\t}\r\n\r\n    \t<\/style>\r\n    \t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6103b10 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6103b10\" data-element_type=\"section\" style=\"border: none; vertical-align: center;\">\r\n\t\t\t<div class=\"elementor-container elementor-column-gap-default\" style=\"border-bottom: 1px solid #002940; padding: 40px 0px 52px 0px;\">\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-3b56bc4\" data-id=\"3b56bc4\" data-element_type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e101a4a elementor-widget elementor-widget-heading\" data-id=\"e101a4a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default post-date\"> 19 novembre 2025<\/h5>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-53ec911 post-info\" data-id=\"53ec911\" data-element_type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d084da elementor-widget elementor-widget-text-editor\" data-id=\"2d084da\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t<style>\/*! elementor - v3.17.0 - 25-10-2023 *\/\r\n\t\t\t\t\t\t\t\t\t.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}\r\n\t\t\t\t\t\t\t\t<\/style>\r\n\t\t\t\t\t\t\t\t<p class=\"post-info\" style=\"font-size: 16px;\"><strong>Revivons ensemble les \u00e9motions de Host 2025<\/strong><\/p>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b76e424 elementor-widget elementor-widget-text-editor\" data-id=\"b76e424\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t<p class=\"post-info\" style=\"font-size: 15px; overflow: hidden; white-space: nowrap; text-overflow: ellipsis; max-width: 700px;\">Silko \u00e0 Host Milano 2025 pr\u00e9sente Pi, LiteBite et FDL.<\/p>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-d318985\" data-id=\"d318985\" data-element_type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e5d842 elementor-align-right elementor-widget elementor-widget-button\" data-id=\"5e5d842\" data-element_type=\"widget\" data-widget_type=\"button.default\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\r\n\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm post-read-button\" href=\"https:\/\/silko.it\/fr\/revivons-ensemble-les-emotions-de-host-2025\/\">\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\" style=\"font-size: 15px;\">LIRE &gt;<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/section>\r\n\r\n\r\n        \t<style type=\"text\/css\">\r\n\r\n    \t\t*{\r\n    \t\t\tfont-family: \"Open Sans\";\r\n    \t\t}\r\n    \t\t.post-date{\r\n    \t\t\tcolor: #D7761E !important;\r\n    \t\t\tfont-size: 20px;\r\n    \t\t}\r\n\r\n    \t\t.post-info{\r\n    \t\t\tcolor: #002940 !important;\r\n    \t\t}\r\n\r\n    \t\t.post-read-button{\r\n    \t\t\tbackground-color: #00000000 !important;\r\n    \t\t\tcolor: #002940 !important;\r\n    \t\t\tpadding: 15px 21px;\r\n    \t\t\tborder: 1px solid #002940 !important;\r\n    \t\t\tborder-radius: 0px;\r\n    \t\t}\r\n\r\n    \t<\/style>\r\n    \t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6103b10 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6103b10\" data-element_type=\"section\" style=\"border: none; vertical-align: center;\">\r\n\t\t\t<div class=\"elementor-container elementor-column-gap-default\" style=\"border-bottom: 1px solid #002940; padding: 40px 0px 52px 0px;\">\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-3b56bc4\" data-id=\"3b56bc4\" data-element_type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e101a4a elementor-widget elementor-widget-heading\" data-id=\"e101a4a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default post-date\"> 27 ao?t 2025<\/h5>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-53ec911 post-info\" data-id=\"53ec911\" data-element_type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d084da elementor-widget elementor-widget-text-editor\" data-id=\"2d084da\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t<style>\/*! elementor - v3.17.0 - 25-10-2023 *\/\r\n\t\t\t\t\t\t\t\t\t.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}\r\n\t\t\t\t\t\t\t\t<\/style>\r\n\t\t\t\t\t\t\t\t<p class=\"post-info\" style=\"font-size: 16px;\"><strong>Silko \u00e0 Host Milano : design et innovation sur sc\u00e8ne<\/strong><\/p>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b76e424 elementor-widget elementor-widget-text-editor\" data-id=\"b76e424\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t<p class=\"post-info\" style=\"font-size: 15px; overflow: hidden; white-space: nowrap; text-overflow: ellipsis; max-width: 700px;\">Design et innovation sur mesure : la cuisine devient une exp\u00e9rience avec Silko \u00e0 Host Milano 2025<\/p>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-d318985\" data-id=\"d318985\" data-element_type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e5d842 elementor-align-right elementor-widget elementor-widget-button\" data-id=\"5e5d842\" data-element_type=\"widget\" data-widget_type=\"button.default\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\r\n\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm post-read-button\" href=\"https:\/\/silko.it\/fr\/silko-a-host-milano-design-et-innovation-sur-scene\/\">\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\" style=\"font-size: 15px;\">LIRE &gt;<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/section>\r\n\r\n\r\n        \t<style type=\"text\/css\">\r\n\r\n    \t\t*{\r\n    \t\t\tfont-family: \"Open Sans\";\r\n    \t\t}\r\n    \t\t.post-date{\r\n    \t\t\tcolor: #D7761E !important;\r\n    \t\t\tfont-size: 20px;\r\n    \t\t}\r\n\r\n    \t\t.post-info{\r\n    \t\t\tcolor: #002940 !important;\r\n    \t\t}\r\n\r\n    \t\t.post-read-button{\r\n    \t\t\tbackground-color: #00000000 !important;\r\n    \t\t\tcolor: #002940 !important;\r\n    \t\t\tpadding: 15px 21px;\r\n    \t\t\tborder: 1px solid #002940 !important;\r\n    \t\t\tborder-radius: 0px;\r\n    \t\t}\r\n\r\n    \t<\/style>\r\n    \t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6103b10 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6103b10\" data-element_type=\"section\" style=\"border: none; vertical-align: center;\">\r\n\t\t\t<div class=\"elementor-container elementor-column-gap-default\" style=\"border-bottom: 1px solid #002940; padding: 40px 0px 52px 0px;\">\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-3b56bc4\" data-id=\"3b56bc4\" data-element_type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e101a4a elementor-widget elementor-widget-heading\" data-id=\"e101a4a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default post-date\"> 30 mai 2025<\/h5>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-53ec911 post-info\" data-id=\"53ec911\" data-element_type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d084da elementor-widget elementor-widget-text-editor\" data-id=\"2d084da\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t<style>\/*! elementor - v3.17.0 - 25-10-2023 *\/\r\n\t\t\t\t\t\t\t\t\t.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}\r\n\t\t\t\t\t\t\t\t<\/style>\r\n\t\t\t\t\t\t\t\t<p class=\"post-info\" style=\"font-size: 16px;\"><strong>Silko a particip\u00e9 au Foodservice Award Italy 2025<\/strong><\/p>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b76e424 elementor-widget elementor-widget-text-editor\" data-id=\"b76e424\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t<p class=\"post-info\" style=\"font-size: 15px; overflow: hidden; white-space: nowrap; text-overflow: ellipsis; max-width: 700px;\">Silko a eu l\u2019honneur de participer en tant que sponsor Silver au prestigieux Foodservice Summit Italy.<\/p>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-d318985\" data-id=\"d318985\" data-element_type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e5d842 elementor-align-right elementor-widget elementor-widget-button\" data-id=\"5e5d842\" data-element_type=\"widget\" data-widget_type=\"button.default\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\r\n\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm post-read-button\" href=\"https:\/\/silko.it\/fr\/silko-a-participe-au-foodservice-award-italy-2025\/\">\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\" style=\"font-size: 15px;\">LIRE &gt;<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/section>\r\n\r\n\r\n        \t<style type=\"text\/css\">\r\n\r\n    \t\t*{\r\n    \t\t\tfont-family: \"Open Sans\";\r\n    \t\t}\r\n    \t\t.post-date{\r\n    \t\t\tcolor: #D7761E !important;\r\n    \t\t\tfont-size: 20px;\r\n    \t\t}\r\n\r\n    \t\t.post-info{\r\n    \t\t\tcolor: #002940 !important;\r\n    \t\t}\r\n\r\n    \t\t.post-read-button{\r\n    \t\t\tbackground-color: #00000000 !important;\r\n    \t\t\tcolor: #002940 !important;\r\n    \t\t\tpadding: 15px 21px;\r\n    \t\t\tborder: 1px solid #002940 !important;\r\n    \t\t\tborder-radius: 0px;\r\n    \t\t}\r\n\r\n    \t<\/style>\r\n    \t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6103b10 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6103b10\" data-element_type=\"section\" style=\"border: none; vertical-align: center;\">\r\n\t\t\t<div class=\"elementor-container elementor-column-gap-default\" style=\"border-bottom: 1px solid #002940; padding: 40px 0px 52px 0px;\">\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-3b56bc4\" data-id=\"3b56bc4\" data-element_type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e101a4a elementor-widget elementor-widget-heading\" data-id=\"e101a4a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default post-date\"> 10 avril 2025<\/h5>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-53ec911 post-info\" data-id=\"53ec911\" data-element_type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d084da elementor-widget elementor-widget-text-editor\" data-id=\"2d084da\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t<style>\/*! elementor - v3.17.0 - 25-10-2023 *\/\r\n\t\t\t\t\t\t\t\t\t.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}\r\n\t\t\t\t\t\t\t\t<\/style>\r\n\t\t\t\t\t\t\t\t<p class=\"post-info\" style=\"font-size: 16px;\"><strong>Cuiseurs et paniers \u00e0 p\u00e2tes<\/strong><\/p>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b76e424 elementor-widget elementor-widget-text-editor\" data-id=\"b76e424\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t<p class=\"post-info\" style=\"font-size: 15px; overflow: hidden; white-space: nowrap; text-overflow: ellipsis; max-width: 700px;\">Le guide ultime des configurations de cuiseur \u00e0 p\u00e2tes.<\/p>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-d318985\" data-id=\"d318985\" data-element_type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e5d842 elementor-align-right elementor-widget elementor-widget-button\" data-id=\"5e5d842\" data-element_type=\"widget\" data-widget_type=\"button.default\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\r\n\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm post-read-button\" href=\"https:\/\/silko.it\/fr\/cuiseurs-et-paniers-a-pates\/\">\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\" style=\"font-size: 15px;\">LIRE &gt;<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/section>\r\n\r\n\r\n        \t<style type=\"text\/css\">\r\n\r\n    \t\t*{\r\n    \t\t\tfont-family: \"Open Sans\";\r\n    \t\t}\r\n    \t\t.post-date{\r\n    \t\t\tcolor: #D7761E !important;\r\n    \t\t\tfont-size: 20px;\r\n    \t\t}\r\n\r\n    \t\t.post-info{\r\n    \t\t\tcolor: #002940 !important;\r\n    \t\t}\r\n\r\n    \t\t.post-read-button{\r\n    \t\t\tbackground-color: #00000000 !important;\r\n    \t\t\tcolor: #002940 !important;\r\n    \t\t\tpadding: 15px 21px;\r\n    \t\t\tborder: 1px solid #002940 !important;\r\n    \t\t\tborder-radius: 0px;\r\n    \t\t}\r\n\r\n    \t<\/style>\r\n    \t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6103b10 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6103b10\" data-element_type=\"section\" style=\"border: none; vertical-align: center;\">\r\n\t\t\t<div class=\"elementor-container elementor-column-gap-default\" style=\"border-bottom: 1px solid #002940; padding: 40px 0px 52px 0px;\">\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-3b56bc4\" data-id=\"3b56bc4\" data-element_type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e101a4a elementor-widget elementor-widget-heading\" data-id=\"e101a4a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default post-date\"> 30 janvier 2025<\/h5>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-53ec911 post-info\" data-id=\"53ec911\" data-element_type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d084da elementor-widget elementor-widget-text-editor\" data-id=\"2d084da\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t<style>\/*! elementor - v3.17.0 - 25-10-2023 *\/\r\n\t\t\t\t\t\t\t\t\t.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}\r\n\t\t\t\t\t\t\t\t<\/style>\r\n\t\t\t\t\t\t\t\t<p class=\"post-info\" style=\"font-size: 16px;\"><strong>Pr\u00e9sentation de Sonika au Sirha : Une R\u00e9volution Culinaire<\/strong><\/p>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b76e424 elementor-widget elementor-widget-text-editor\" data-id=\"b76e424\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t<p class=\"post-info\" style=\"font-size: 15px; overflow: hidden; white-space: nowrap; text-overflow: ellipsis; max-width: 700px;\">Lors du Sirha, l'\u00e9v\u00e9nement phare de l'innovation culinaire, Waveco et Silko, du groupe Ali, ont d\u00e9voil\u00e9 leur collaboration r\u00e9volutionnaire. Ensemble, ils ont cr\u00e9\u00e9 Sonika, un produit qui promet de transformer le paysage culinaire mondial. <\/p>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-d318985\" data-id=\"d318985\" data-element_type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e5d842 elementor-align-right elementor-widget elementor-widget-button\" data-id=\"5e5d842\" data-element_type=\"widget\" data-widget_type=\"button.default\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\r\n\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm post-read-button\" href=\"https:\/\/silko.it\/fr\/presentation-de-sonika-au-sirha-une-revolution-culinaire\/\">\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\" style=\"font-size: 15px;\">LIRE &gt;<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/section>\r\n\r\n\r\n        \t<style type=\"text\/css\">\r\n\r\n    \t\t*{\r\n    \t\t\tfont-family: \"Open Sans\";\r\n    \t\t}\r\n    \t\t.post-date{\r\n    \t\t\tcolor: #D7761E !important;\r\n    \t\t\tfont-size: 20px;\r\n    \t\t}\r\n\r\n    \t\t.post-info{\r\n    \t\t\tcolor: #002940 !important;\r\n    \t\t}\r\n\r\n    \t\t.post-read-button{\r\n    \t\t\tbackground-color: #00000000 !important;\r\n    \t\t\tcolor: #002940 !important;\r\n    \t\t\tpadding: 15px 21px;\r\n    \t\t\tborder: 1px solid #002940 !important;\r\n    \t\t\tborder-radius: 0px;\r\n    \t\t}\r\n\r\n    \t<\/style>\r\n    \t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6103b10 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6103b10\" data-element_type=\"section\" style=\"border: none; vertical-align: center;\">\r\n\t\t\t<div class=\"elementor-container elementor-column-gap-default\" style=\"border-bottom: 1px solid #002940; padding: 40px 0px 52px 0px;\">\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-3b56bc4\" data-id=\"3b56bc4\" data-element_type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e101a4a elementor-widget elementor-widget-heading\" data-id=\"e101a4a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default post-date\"> 19 juillet 2024<\/h5>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-53ec911 post-info\" data-id=\"53ec911\" data-element_type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d084da elementor-widget elementor-widget-text-editor\" data-id=\"2d084da\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t<style>\/*! elementor - v3.17.0 - 25-10-2023 *\/\r\n\t\t\t\t\t\t\t\t\t.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}\r\n\t\t\t\t\t\t\t\t<\/style>\r\n\t\t\t\t\t\t\t\t<p class=\"post-info\" style=\"font-size: 16px;\"><strong>Silko \u00e0 Gulfhost 2024<\/strong><\/p>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b76e424 elementor-widget elementor-widget-text-editor\" data-id=\"b76e424\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t<p class=\"post-info\" style=\"font-size: 15px; overflow: hidden; white-space: nowrap; text-overflow: ellipsis; max-width: 700px;\">Silko participera au salon GulfHost Dubai du 5 au 7 novembre 2024, le principal salon de la r\u00e9gion MENA d\u00e9di\u00e9 aux \u00e9quipements de restauration. Nous vous attendons avec nos technologies dans le Hall Za\u2019abeel 2, Stand Z2-B18, au World Trade Centre Za\u2019abeel - Duba\u00ef - \u00c9mirats Arabes Unis.<\/p>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-d318985\" data-id=\"d318985\" data-element_type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e5d842 elementor-align-right elementor-widget elementor-widget-button\" data-id=\"5e5d842\" data-element_type=\"widget\" data-widget_type=\"button.default\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\r\n\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm post-read-button\" href=\"https:\/\/silko.it\/fr\/silko-a-gulfhost-2024\/\">\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\" style=\"font-size: 15px;\">LIRE &gt;<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/section>\r\n\r\n\r\n        \t<style type=\"text\/css\">\r\n\r\n    \t\t*{\r\n    \t\t\tfont-family: \"Open Sans\";\r\n    \t\t}\r\n    \t\t.post-date{\r\n    \t\t\tcolor: #D7761E !important;\r\n    \t\t\tfont-size: 20px;\r\n    \t\t}\r\n\r\n    \t\t.post-info{\r\n    \t\t\tcolor: #002940 !important;\r\n    \t\t}\r\n\r\n    \t\t.post-read-button{\r\n    \t\t\tbackground-color: #00000000 !important;\r\n    \t\t\tcolor: #002940 !important;\r\n    \t\t\tpadding: 15px 21px;\r\n    \t\t\tborder: 1px solid #002940 !important;\r\n    \t\t\tborder-radius: 0px;\r\n    \t\t}\r\n\r\n    \t<\/style>\r\n    \t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6103b10 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6103b10\" data-element_type=\"section\" style=\"border: none; vertical-align: center;\">\r\n\t\t\t<div class=\"elementor-container elementor-column-gap-default\" style=\"border-bottom: 1px solid #002940; padding: 40px 0px 52px 0px;\">\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-3b56bc4\" data-id=\"3b56bc4\" data-element_type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e101a4a elementor-widget elementor-widget-heading\" data-id=\"e101a4a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default post-date\"> 22 janvier 2024<\/h5>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-53ec911 post-info\" data-id=\"53ec911\" data-element_type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d084da elementor-widget elementor-widget-text-editor\" data-id=\"2d084da\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t<style>\/*! elementor - v3.17.0 - 25-10-2023 *\/\r\n\t\t\t\t\t\t\t\t\t.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}\r\n\t\t\t\t\t\t\t\t<\/style>\r\n\t\t\t\t\t\t\t\t<p class=\"post-info\" style=\"font-size: 16px;\"><strong>Nouveaux bureaux!<\/strong><\/p>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b76e424 elementor-widget elementor-widget-text-editor\" data-id=\"b76e424\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t<p class=\"post-info\" style=\"font-size: 15px; overflow: hidden; white-space: nowrap; text-overflow: ellipsis; max-width: 700px;\">Nous avons emm\u00e9nag\u00e9 dans le nouveau si\u00e8ge du complexe industriel de Franco Marinotti, qui comprend 250 m\u00e8tres carr\u00e9s de bureaux et 3 200 m\u00e8tres carr\u00e9s d'espace de production. Les travaux de restauration ont \u00e9gay\u00e9 l'environnement, en l'int\u00e9grant au paysage urbain et en offrant des vues sur le fleuve.<\/p>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-d318985\" data-id=\"d318985\" data-element_type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e5d842 elementor-align-right elementor-widget elementor-widget-button\" data-id=\"5e5d842\" data-element_type=\"widget\" data-widget_type=\"button.default\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\r\n\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm post-read-button\" href=\"https:\/\/silko.it\/fr\/nouveaux-bureaux\/\">\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\" style=\"font-size: 15px;\">LIRE &gt;<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/section>\r\n\r\n\r\n        \t<style type=\"text\/css\">\r\n\r\n    \t\t*{\r\n    \t\t\tfont-family: \"Open Sans\";\r\n    \t\t}\r\n    \t\t.post-date{\r\n    \t\t\tcolor: #D7761E !important;\r\n    \t\t\tfont-size: 20px;\r\n    \t\t}\r\n\r\n    \t\t.post-info{\r\n    \t\t\tcolor: #002940 !important;\r\n    \t\t}\r\n\r\n    \t\t.post-read-button{\r\n    \t\t\tbackground-color: #00000000 !important;\r\n    \t\t\tcolor: #002940 !important;\r\n    \t\t\tpadding: 15px 21px;\r\n    \t\t\tborder: 1px solid #002940 !important;\r\n    \t\t\tborder-radius: 0px;\r\n    \t\t}\r\n\r\n    \t<\/style>\r\n    \t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6103b10 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6103b10\" data-element_type=\"section\" style=\"border: none; vertical-align: center;\">\r\n\t\t\t<div class=\"elementor-container elementor-column-gap-default\" style=\"border-bottom: 1px solid #002940; padding: 40px 0px 52px 0px;\">\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-3b56bc4\" data-id=\"3b56bc4\" data-element_type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e101a4a elementor-widget elementor-widget-heading\" data-id=\"e101a4a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default post-date\"> 10 ao?t 2021<\/h5>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-53ec911 post-info\" data-id=\"53ec911\" data-element_type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d084da elementor-widget elementor-widget-text-editor\" data-id=\"2d084da\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t<style>\/*! elementor - v3.17.0 - 25-10-2023 *\/\r\n\t\t\t\t\t\t\t\t\t.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}\r\n\t\t\t\t\t\t\t\t<\/style>\r\n\t\t\t\t\t\t\t\t<p class=\"post-info\" style=\"font-size: 16px;\"><strong>Silko \u00e0 Host 2021 Milano\/ Pad 5 - Stand H17<\/strong><\/p>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b76e424 elementor-widget elementor-widget-text-editor\" data-id=\"b76e424\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t<p class=\"post-info\" style=\"font-size: 15px; overflow: hidden; white-space: nowrap; text-overflow: ellipsis; max-width: 700px;\">Silko \u00e0 la prochaine et tr\u00e8s attendue \u00e9dition de Host Milano 2021 qui se tiendra du 22 au 26 octobre 2021.<\/p>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-d318985\" data-id=\"d318985\" data-element_type=\"column\">\r\n\t\t\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\r\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e5d842 elementor-align-right elementor-widget elementor-widget-button\" data-id=\"5e5d842\" data-element_type=\"widget\" data-widget_type=\"button.default\">\r\n\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\r\n\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\r\n\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm post-read-button\" href=\"https:\/\/silko.it\/fr\/silko-a-host-2021-milano-pad-5-stand-h17\/\">\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\" style=\"font-size: 15px;\">LIRE &gt;<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t<\/section>\r\n\r\n\r\n    <\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8481aaf elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8481aaf\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f9adc0f\" data-id=\"f9adc0f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ff10c03 elementor-widget elementor-widget-heading\" data-id=\"ff10c03\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Vous souhaitez \u00eatre tenu au courant de l'actualit\u00e9 de Silko ?<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-db71afb elementor-widget elementor-widget-text-editor\" data-id=\"db71afb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Abonnez-vous \u00e0 la newsletter!<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ef6f75 elementor-widget elementor-widget-shortcode\" data-id=\"8ef6f75\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><script>(function() {\n\twindow.mc4wp = window.mc4wp || {\n\t\tlisteners: [],\n\t\tforms: {\n\t\t\ton: function(evt, cb) {\n\t\t\t\twindow.mc4wp.listeners.push(\n\t\t\t\t\t{\n\t\t\t\t\t\tevent   : evt,\n\t\t\t\t\t\tcallback: cb\n\t\t\t\t\t}\n\t\t\t\t);\n\t\t\t}\n\t\t}\n\t}\n})();\n<\/script><!-- Mailchimp for WordPress v4.10.2 - https:\/\/wordpress.org\/plugins\/mailchimp-for-wp\/ --><form id=\"mc4wp-form-1\" class=\"mc4wp-form mc4wp-form-4490\" method=\"post\" data-id=\"4490\" data-name=\"Newsletter\" ><div class=\"mc4wp-form-fields\"><div id=\"newsletter\" style=\" display: flex;\r\n             align-items: center;\r\n             justify-content: center;\r\n             height: 40px;\r\n             border: 1px solid #002940;\r\n             background: #FFFFFF;\r\n             padding: 5px;\r\n             left: auto;\r\n            right: auto;\">\r\n  <input id=\"newsletter-input\" type=\"email\" name=\"EMAIL\" placeholder=\"\" style=\"  \r\n    \t          border: none;\r\n                  text-align: center;\r\n                  font-family: Open Sans, Regular;\r\n                  font-size: 14px;\r\n                  color: #002940;\r\n                  opacity: 0.5;\r\n                  \r\n                width: 100%;\" required=\"\">\r\n  <button type=\"submit\" class=\"btn-newsletter\">&gt;<\/button>\r\n<\/div>\r\n\r\n<script>\r\n  \/\/ Funzione per ottenere la lingua dalla URL\r\nfunction getLanguageFromURL() {\r\n  const url = window.location.href;\r\n  if (url.includes(\"\/de\/\")) {\r\n    return \"de\"; \/\/ Tedesco\r\n  } else if (url.includes(\"\/fr\/\")) {\r\n    return \"fr\"; \/\/ Francese\r\n  } else if (url.includes(\"\/en\/\")) {\r\n    return \"en\"; \/\/ Inglese\r\n  } else {\r\n    return \"it\"; \/\/ Italiano\r\n  }\r\n}\r\n\r\n\/\/ Funzione per impostare il placeholder in base alla lingua\r\nfunction setPlaceholderByLanguage() {\r\n  const language = getLanguageFromURL();\r\n  const input = document.getElementById(\"newsletter-input\");\r\n  let placeholderText = \"\";\r\n\r\n  switch (language) {\r\n    case \"de\":\r\n      placeholderText = \"Ihre E-Mail eingeben\";\r\n      break;\r\n    case \"fr\":\r\n      placeholderText = \"Saisissez votre adresse \u00e9lectronique\";\r\n      break;\r\n    case \"en\":\r\n      placeholderText = \"Enter your email\";\r\n      break;\r\n    case \"it\":\r\n    default:\r\n      placeholderText = \"Inserisci la tua email\";\r\n  }\r\n\r\n  input.setAttribute(\"placeholder\", placeholderText);\r\n}\r\n\r\n\/\/ Chiamata alla funzione per impostare il placeholder quando il documento \u00e8 pronto\r\ndocument.addEventListener(\"DOMContentLoaded\", function() {\r\n  setPlaceholderByLanguage();\r\n});\r\n\r\n<\/script><\/div><label style=\"display: none !important;\">Laissez ce champ vide si vous \u00eates humain\u00a0: <input type=\"text\" name=\"_mc4wp_honeypot\" value=\"\" tabindex=\"-1\" autocomplete=\"off\" \/><\/label><input type=\"hidden\" name=\"_mc4wp_timestamp\" value=\"1778682774\" \/><input type=\"hidden\" name=\"_mc4wp_form_id\" value=\"4490\" \/><input type=\"hidden\" name=\"_mc4wp_form_element_id\" value=\"mc4wp-form-1\" \/><div class=\"mc4wp-response\"><\/div><\/form><!-- \/ Mailchimp for WordPress Plugin --><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-91bb098 policy-link elementor-widget elementor-widget-text-editor\" data-id=\"91bb098\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/silko.it\/fr\/legal-notices-and-gdpr-privacy-policy\/\" target=\"_blank\">Legal Notices and GDPR Privacy Policy<\/a><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>News Vous souhaitez \u00eatre tenu au courant de l&rsquo;actualit\u00e9 de Silko ? Abonnez-vous \u00e0 la newsletter! Legal Notices and GDPR Privacy Policy<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_joinchat":[],"footnotes":""},"class_list":["post-6396","page","type-page","status-publish","hentry","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>News Old - Silko<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/silko.it\/news-old\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"News Old - Silko\" \/>\n<meta property=\"og:description\" content=\"News Vous souhaitez \u00eatre tenu au courant de l&rsquo;actualit\u00e9 de Silko ? Abonnez-vous \u00e0 la newsletter! Legal Notices and GDPR Privacy Policy\" \/>\n<meta property=\"og:url\" content=\"https:\/\/silko.it\/news-old\/\" \/>\n<meta property=\"og:site_name\" content=\"Silko\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SilkoAli\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-24T08:16:23+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/silko.it\/news-old\/\",\"url\":\"https:\/\/silko.it\/news-old\/\",\"name\":\"News Old - Silko\",\"isPartOf\":{\"@id\":\"https:\/\/silko.it\/#website\"},\"datePublished\":\"2023-10-19T14:31:14+00:00\",\"dateModified\":\"2024-07-24T08:16:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/silko.it\/news-old\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/silko.it\/news-old\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/silko.it\/news-old\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/silko.it\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News Old\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/silko.it\/#website\",\"url\":\"https:\/\/silko.it\/\",\"name\":\"https:\/\/silko.it\/\",\"description\":\"Cucine professionali e arredi per la ristorazione\",\"publisher\":{\"@id\":\"https:\/\/silko.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/silko.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/silko.it\/#organization\",\"name\":\"Silko - Cucine professionali e attrezzature per la ristorazione\",\"url\":\"https:\/\/silko.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/silko.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/silko.it\/wp-content\/uploads\/2023\/08\/silko-logo.webp\",\"contentUrl\":\"https:\/\/silko.it\/wp-content\/uploads\/2023\/08\/silko-logo.webp\",\"width\":186,\"height\":56,\"caption\":\"Silko - Cucine professionali e attrezzature per la ristorazione\"},\"image\":{\"@id\":\"https:\/\/silko.it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/SilkoAli\/\",\"https:\/\/www.instagram.com\/silko_ali\/\",\"https:\/\/www.linkedin.com\/company\/silko-ali-s.p.a.\/\",\"https:\/\/www.youtube.com\/user\/SilkoAli\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"News Old - Silko","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/silko.it\/news-old\/","og_locale":"fr_FR","og_type":"article","og_title":"News Old - Silko","og_description":"News Vous souhaitez \u00eatre tenu au courant de l&rsquo;actualit\u00e9 de Silko ? Abonnez-vous \u00e0 la newsletter! Legal Notices and GDPR Privacy Policy","og_url":"https:\/\/silko.it\/news-old\/","og_site_name":"Silko","article_publisher":"https:\/\/www.facebook.com\/SilkoAli\/","article_modified_time":"2024-07-24T08:16:23+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/silko.it\/news-old\/","url":"https:\/\/silko.it\/news-old\/","name":"News Old - Silko","isPartOf":{"@id":"https:\/\/silko.it\/#website"},"datePublished":"2023-10-19T14:31:14+00:00","dateModified":"2024-07-24T08:16:23+00:00","breadcrumb":{"@id":"https:\/\/silko.it\/news-old\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/silko.it\/news-old\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/silko.it\/news-old\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/silko.it\/fr\/"},{"@type":"ListItem","position":2,"name":"News Old"}]},{"@type":"WebSite","@id":"https:\/\/silko.it\/#website","url":"https:\/\/silko.it\/","name":"https:\/\/silko.it\/","description":"Cucine professionali e arredi per la ristorazione","publisher":{"@id":"https:\/\/silko.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/silko.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/silko.it\/#organization","name":"Silko - Cucine professionali e attrezzature per la ristorazione","url":"https:\/\/silko.it\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/silko.it\/#\/schema\/logo\/image\/","url":"https:\/\/silko.it\/wp-content\/uploads\/2023\/08\/silko-logo.webp","contentUrl":"https:\/\/silko.it\/wp-content\/uploads\/2023\/08\/silko-logo.webp","width":186,"height":56,"caption":"Silko - Cucine professionali e attrezzature per la ristorazione"},"image":{"@id":"https:\/\/silko.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SilkoAli\/","https:\/\/www.instagram.com\/silko_ali\/","https:\/\/www.linkedin.com\/company\/silko-ali-s.p.a.\/","https:\/\/www.youtube.com\/user\/SilkoAli"]}]}},"_links":{"self":[{"href":"https:\/\/silko.it\/fr\/wp-json\/wp\/v2\/pages\/6396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/silko.it\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/silko.it\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/silko.it\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/silko.it\/fr\/wp-json\/wp\/v2\/comments?post=6396"}],"version-history":[{"count":11,"href":"https:\/\/silko.it\/fr\/wp-json\/wp\/v2\/pages\/6396\/revisions"}],"predecessor-version":[{"id":14951,"href":"https:\/\/silko.it\/fr\/wp-json\/wp\/v2\/pages\/6396\/revisions\/14951"}],"wp:attachment":[{"href":"https:\/\/silko.it\/fr\/wp-json\/wp\/v2\/media?parent=6396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}